{"id":3767,"date":"2024-02-05T14:12:17","date_gmt":"2024-02-05T17:12:17","guid":{"rendered":"https:\/\/conssanpaolo.esteri.it\/?p=3767"},"modified":"2024-02-05T14:13:04","modified_gmt":"2024-02-05T17:13:04","slug":"iyt","status":"publish","type":"post","link":"https:\/\/conssanpaolo.esteri.it\/it\/news\/dal_consolato\/2024\/02\/iyt\/","title":{"rendered":"&#8220;Invest Your Talent in Italy&#8221; (IYT) &#8211; Anno Accademico 2024\/2025"},"content":{"rendered":"<p>Si informa che \u00e8 stato aperto il bando per l&#8217;assegnazione delle borse di studio &#8220;Invest Your Talent in Italy&#8221; (IYT) relative all&#8217;Anno Accademico 2024\/2025. Come per le passate edizioni, le candidature dovranno essere inviate dagli studenti per via telematica, accedendo alla piattaforma dedicata:<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/investyourtalentapplication.esteri.it\/sitoinvestyourtalentapplication\/progetto.asp\">https:\/\/investyourtalentapplication.esteri.it\/sitoinvestyourtalentapplication\/progetto.asp<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>La scadenza per potersi candidare \u00e8 stata fissata al 1 marzo 2024.<\/p>\n<p>Si informa altres\u00ec che le Universit\u00e0 degli Studi di Brescia, di Firenze, della Tuscia, di Padova, di Parma e di Pisa hanno manifestato la disponibilit\u00e0 a finanziare borse di studio a favore dei candidati vincitori che abbiano scelto di iscriversi presso i predetti Atenei partecipanti al Programma.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Si informa che \u00e8 stato aperto il bando per l&#8217;assegnazione delle borse di studio &#8220;Invest Your Talent in Italy&#8221; (IYT) relative all&#8217;Anno Accademico 2024\/2025. Come per le passate edizioni, le candidature dovranno essere inviate dagli studenti per via telematica, accedendo alla piattaforma dedicata: &nbsp; https:\/\/investyourtalentapplication.esteri.it\/sitoinvestyourtalentapplication\/progetto.asp &nbsp; La scadenza per potersi candidare \u00e8 stata fissata al [&hellip;]","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-3767","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/conssanpaolo.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conssanpaolo.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conssanpaolo.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conssanpaolo.esteri.it\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conssanpaolo.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=3767"}],"version-history":[{"count":2,"href":"https:\/\/conssanpaolo.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3767\/revisions"}],"predecessor-version":[{"id":3776,"href":"https:\/\/conssanpaolo.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3767\/revisions\/3776"}],"wp:attachment":[{"href":"https:\/\/conssanpaolo.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=3767"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conssanpaolo.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=3767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}